{"id":1606,"date":"2026-07-08T15:28:44","date_gmt":"2026-07-08T15:28:44","guid":{"rendered":"https:\/\/internationalafricanmobilization.com\/e-news\/july-2026\/"},"modified":"2026-07-15T02:18:24","modified_gmt":"2026-07-15T02:18:24","slug":"july-2026","status":"publish","type":"page","link":"https:\/\/internationalafricanmobilization.com\/sw\/e-news\/july-2026\/","title":{"rendered":"Taarifa Pendwa za Mtandaoni \u2014 Julai 2026"},"content":{"rendered":"<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\" bgcolor=\"#f5f5f5\" style=\"background-color:#f5f5f5;\">\n<tr>\n<td align=\"center\" style=\"padding:30px 20px;\">\n<table width=\"620\" cellpadding=\"0\" cellspacing=\"0\" style=\"background-color:#ffffff;max-width:620px;width:100%;\">\n<!-- HEADER --><\/p>\n<tr>\n<td style=\"background-color:#660F11;padding:30px 40px;text-align:center;\">\n<p style=\"margin:0;color:#B9AB84;font-family:Georgia,serif;font-size:13px;letter-spacing:2px;text-transform:uppercase;\">Uhamasishaji wa Kimataifa wa Kiafrika<\/p>\n<h1 style=\"margin:12px 0 0 0;color:#ffffff;font-family:Georgia,serif;font-size:28px;font-weight:bold;line-height:1.3;\">Taarifa Pendwa za Mtandaoni \u2014 Julai 2026<\/h1>\n<\/td>\n<\/tr>\n<p><!-- INTRO --><\/p>\n<tr>\n<td style=\"padding:36px 40px 20px 40px;\">\n<p style=\"margin:0 0 18px 0;color:#222222;font-family:Georgia,serif;font-size:16px;line-height:1.8;\">Marafiki,<\/p>\n<p style=\"margin:0;color:#222222;font-family:Georgia,serif;font-size:16px;line-height:1.8;\">Tarehe hii nataka kushiriki ripoti kutoka kaskazini mwa Ghana iliyonishtua. Mungu anafanya kwa njia ambazo Yeye pekee anaweza kueleza.<\/p>\n<\/td>\n<\/tr>\n<p><!-- DIVIDER --><\/p>\n<tr>\n<td style=\"padding:0 40px;\">\n<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\">\n<tr>\n<td style=\"background-color:#660F11;height:3px;\"><\/td>\n<\/tr>\n<\/table>\n<\/td>\n<\/tr>\n<p><!-- GHANA SECTION --><\/p>\n<tr>\n<td style=\"padding:30px 40px 10px 40px;\">\n<p style=\"margin:0 0 6px 0;color:#B9AB84;font-family:Georgia,serif;font-size:12px;letter-spacing:2px;text-transform:uppercase;\">Ripoti ya Shambani \u2014 Ghana ya Kaskazini<\/p>\n<h2 style=\"margin:0 0 20px 0;color:#660F11;font-family:Georgia,serif;font-size:22px;font-weight:bold;line-height:1.3;\">Ndoto, Jitu, na Mwanamke Aliyejiri Mkunjo<\/h2>\n<p><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/enrichlabs-public-assets\/truff%40mynorthside.com\/files\/.uploads\/1783518503584-WhatsApp_Image_2026-07-02_at_07.16.35.jpeg\" width=\"540\" style=\"display:block;width:100%;max-width:540px;height:auto;margin:0 0 24px 0;border-radius:4px;\" alt=\"Community gathered in northern Ghana\" class=\"no-lazyload\" \/><\/p>\n<p style=\"margin:0 0 18px 0;color:#222222;font-family:Georgia,serif;font-size:16px;line-height:1.8;\">Isaac ni mtu nilifanya naye kazi kwa miaka 14 kaskazini mwa Ghana. Kwa uongozi wa Mungu, sasa anasimamia makundi 3,000 ya Mafunzo ya Biblia ya Utambuzi nchini Ghana na makundi 100 katika kila moja ya nchi 13 nyingine za Afrika Magharibi \u2014 zaidi ya makundi 4,300 kote barani, yakigusa maisha ya makumi ya maelfu.<\/p>\n<p style=\"margin:0 0 18px 0;color:#222222;font-family:Georgia,serif;font-size:16px;line-height:1.8;\">Katika wiki tatu zilizopita, Isaac amefiwa na kaka yake na dada yake. Nilimpigia simu leo asubuhi kumtia moyo. Ana huzuni kubwa, hata hivyo bado anasimama.<\/p>\n<p style=\"margin:0 0 18px 0;color:#222222;font-family:Georgia,serif;font-size:16px;line-height:1.8;\">Tafadhali ombeni sana kwa ajili ya watoto. Nduguye aliacha watoto 7. Dada yake aliacha watoto 8. Maisha kumi na matano ambayo hayajakua sasa yanakabiliwa na hatma isiyo na uhakika, na familia ya Isaac inachukua jukumu la kuhakikisha wanapendwa na kutunzwa.<\/p>\n<p style=\"margin:0 0 18px 0;color:#222222;font-family:Georgia,serif;font-size:16px;line-height:1.8;\">Katika hali hii ya huzuni, <strong style=\"color:#660F11;\">Mungu anasonga.<\/strong><\/p>\n<p style=\"margin:0 0 18px 0;color:#222222;font-family:Georgia,serif;font-size:16px;line-height:1.8;\">Nduguye mdogo na dada yake Isaac hivi karibuni wote wawili wamempa Kristo kama Bwana na Mwokozi wao. Na mama yake Isaac \u2014 ambaye amekuwa akipinga kwa muda mrefu \u2014 sasa anazungumza vizuri kuhusu Wakristo. Kuna kitu kinabadilika moyoni mwake.<\/p>\n<p style=\"margin:0 0 18px 0;color:#222222;font-family:Georgia,serif;font-size:16px;line-height:1.8;\">Kisha kuna hadithi hii.<\/p>\n<p style=\"margin:0 0 18px 0;color:#222222;font-family:Georgia,serif;font-size:16px;line-height:1.8;\">Mwanamke mmoja katika jamii ya Isaka\u2014ambaye alikuwa amefungwa kwa injili\u2014alikuwa na ndoto. Ndotoni, jitu lilionekana na lilikuwa karibu kumwua. Alimwona Isaka akimshinda jitu hilo. Alimjia mara moja na kumuuliza ni nini alichopaswa kufanya.<\/p>\n<p style=\"margin:0 0 18px 0;color:#222222;font-family:Georgia,serif;font-size:16px;line-height:1.8;\">Isaac alimwambia: hakuwa yeye. Alikuwa Kristo ambaye alimtaka amfuate Yeye.<\/p>\n<p style=\"margin:0 0 18px 0;color:#222222;font-family:Georgia,serif;font-size:16px;line-height:1.8;\">Alikuwa na wasiwasi mmoja tu \u2014 mwanawe mkubwa. Je, angekubali uamuzi wake? Alipomueleza kuhusu ndoto hiyo, jibu lake lilikuwa la haraka. Kwa sababu ya ndoto hiyo, hakuwa na shida na yeye kumfuata Yesu.<\/p>\n<p style=\"margin:0 0 30px 0;color:#222222;font-family:Georgia,serif;font-size:16px;line-height:1.8;\"><strong style=\"color:#660F11;\">Mungu pekee huandaa mioyo. Jukumu letu ni kutambua kile ambacho tayari anakifanya.<\/strong><\/p>\n<\/td>\n<\/tr>\n<p><!-- PRAYER BOX --><\/p>\n<tr>\n<td style=\"padding:0 40px 30px 40px;\">\n<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\">\n<tr>\n<td style=\"background-color:#660F11;padding:24px 28px;\">\n<p style=\"margin:0 0 12px 0;color:#B9AB84;font-family:Georgia,serif;font-size:12px;letter-spacing:2px;text-transform:uppercase;\">Tafadhaliomba<\/p>\n<p style=\"margin:0 0 8px 0;color:#ffffff;font-family:Georgia,serif;font-size:15px;line-height:1.7;\">\u2022 Kwa Isaac anapoomboleza kifo cha kaka na dada yake<\/p>\n<p style=\"margin:0 0 8px 0;color:#ffffff;font-family:Georgia,serif;font-size:15px;line-height:1.7;\">\u2022 Kwa watoto 15 walioachwa \u2014 7 kutoka kwa kaka yake, 8 kutoka kwa dada yake<\/p>\n<p style=\"margin:0 0 8px 0;color:#ffffff;font-family:Georgia,serif;font-size:15px;line-height:1.7;\">\u2022 Kwa mama yake Isaac \u2014 kwamba angechukua hatua ya mwisho ya imani<\/p>\n<p style=\"margin:0 0 8px 0;color:#ffffff;font-family:Georgia,serif;font-size:15px;line-height:1.7;\">\u2022 Kwa mwanamke yule kutoka katika ndoto \u2014 kwamba imani yake mpya ikue na kuenea<\/p>\n<p style=\"margin:0;color:#ffffff;font-family:Georgia,serif;font-size:15px;line-height:1.7;\">\u2022 Kwa nguvu za Isaac anaposimamia vikundi 4,300+ kote Afrika Magharibi<\/p>\n<\/td>\n<\/tr>\n<\/table>\n<\/td>\n<\/tr>\n<p><!-- DIVIDER --><\/p>\n<tr>\n<td style=\"padding:0 40px;\">\n<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\">\n<tr>\n<td style=\"background-color:#e0e0e0;height:1px;\"><\/td>\n<\/tr>\n<\/table>\n<\/td>\n<\/tr>\n<p><!-- GIVE CTA --><\/p>\n<tr>\n<td style=\"padding:28px 40px;text-align:center;\">\n<p style=\"margin:0 0 14px 0;color:#4a0b0d;font-family:Georgia,serif;font-size:15px;line-height:1.7;\">Mchango wako unaunga mkono kazi inayofanyika Afrika Magharibi na kwingineko. Unaweza kuondoa kodi na unasimamiwa na Kanisa la Kikristo la Northside.<\/p>\n<p><a href=\"https:\/\/pushpay.com\/g\/northsidechristianchurch\" style=\"display:inline-block;background-color:#660F11;color:#ffffff;font-family:Georgia,serif;font-size:15px;font-weight:bold;text-decoration:none;padding:12px 30px;border-radius:3px;\">Toa Sasa<\/a>\n<\/td>\n<\/tr>\n<p><!-- DIVIDER --><\/p>\n<tr>\n<td style=\"padding:0 40px;\">\n<table width=\"100%\" cellpadding=\"0\" cellspacing=\"0\">\n<tr>\n<td style=\"background-color:#e0e0e0;height:1px;\"><\/td>\n<\/tr>\n<\/table>\n<\/td>\n<\/tr>\n<p><!-- SIGNATURE --><\/p>\n<tr>\n<td style=\"padding:28px 40px 30px 40px;\">\n<p style=\"margin:0 0 4px 0;color:#222222;font-family:Georgia,serif;font-size:15px;\">Terry Ruff<\/p>\n<p style=\"margin:0 0 4px 0;color:#888888;font-family:Georgia,serif;font-size:13px;\">Mkufunzi\/Kocha wa DMM Catalyst &amp; Z\u00fame<\/p>\n<p style=\"margin:0;\"><a href=\"https:\/\/internationalafricanmobilization.com\/sw\/\" style=\"color:#660F11;font-family:Georgia,serif;font-size:13px;text-decoration:none;\">internationalafricanmobilization.com<\/a><\/p>\n<\/td>\n<\/tr>\n<p><!-- FOOTER --><\/p>\n<tr>\n<td style=\"background-color:#f5f5f5;padding:20px 40px;text-align:center;border-top:1px solid #e0e0e0;\">\n<p style=\"margin:0 0 8px 0;color:#888888;font-family:Georgia,serif;font-size:12px;\">Ipate katika kikasha chako cha barua pepe kila mwezi:<\/p>\n<p><a href=\"https:\/\/gem.godaddy.com\/signups\/1aaf77c8f5174f7c9a077873c1da0bc8\/join\" style=\"color:#660F11;font-family:Georgia,serif;font-size:12px;text-decoration:underline;\">Jiandikishe kupitia GoDaddy<\/a> &nbsp;|&nbsp;<br \/>\n<a href=\"https:\/\/www.linkedin.com\/build-relation\/newsletter-follow?entityUrn=7469016169262305280\" style=\"color:#660F11;font-family:Georgia,serif;font-size:12px;text-decoration:underline;\">Tumia LinkedIn<\/a>\n<\/td>\n<\/tr>\n<\/table>\n<\/td>\n<\/tr>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>International African Mobilization E-News Update &mdash; July 2026 Friends, This month I want to share a report from northern Ghana that stopped me in my tracks. God is moving in ways only He can explain. Field Report &mdash; Northern Ghana A Dream, a Giant, and a Woman Who Came Running Isaac is the man I&hellip;<\/p>","protected":false},"author":1,"featured_media":1266,"parent":15,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-1606","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>E-News Update \u2014 July 2026 - International African Mobilization<\/title>\n<meta name=\"description\" content=\"International African Mobilization&#039;s July 2026 ministry update: answered prayers, new groups, and what&#039;s ahead.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/internationalafricanmobilization.com\/sw\/e-news\/july-2026\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"E-News Update \u2014 July 2026 - International African Mobilization\" \/>\n<meta property=\"og:description\" content=\"International African Mobilization&#039;s July 2026 ministry update: answered prayers, new groups, and what&#039;s ahead.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/internationalafricanmobilization.com\/sw\/e-news\/july-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"International African Mobilization\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T02:18:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/internationalafricanmobilization.com\/wp-content\/uploads\/2026\/07\/iam-hero.png.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/ur\\\/e-news\\\/july-2026\\\/\",\"url\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/ur\\\/e-news\\\/july-2026\\\/\",\"name\":\"E-News Update \u2014 July 2026 - International African Mobilization\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/ur\\\/e-news\\\/july-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/ur\\\/e-news\\\/july-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/iam-hero.png.jpg\",\"datePublished\":\"2026-07-08T15:28:44+00:00\",\"dateModified\":\"2026-07-15T02:18:24+00:00\",\"description\":\"International African Mobilization's July 2026 ministry update: answered prayers, new groups, and what's ahead.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/ur\\\/e-news\\\/july-2026\\\/#breadcrumb\"},\"inLanguage\":\"sw\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/internationalafricanmobilization.com\\\/ur\\\/e-news\\\/july-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sw\",\"@id\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/ur\\\/e-news\\\/july-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/iam-hero.png.jpg\",\"contentUrl\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/iam-hero.png.jpg\",\"width\":1024,\"height\":680},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/ur\\\/e-news\\\/july-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"E-News\",\"item\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/ur\\\/e-news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"E-News Update \u2014 July 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/#website\",\"url\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/\",\"name\":\"International African Mobilization\",\"description\":\"Glorifying God, Disciples Making Movements (DMM)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sw\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"E-News Update \u2014 July 2026 - International African Mobilization","description":"International African Mobilization's July 2026 ministry update: answered prayers, new groups, and what's ahead.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/internationalafricanmobilization.com\/sw\/e-news\/july-2026\/","og_locale":"en_US","og_type":"article","og_title":"E-News Update \u2014 July 2026 - International African Mobilization","og_description":"International African Mobilization's July 2026 ministry update: answered prayers, new groups, and what's ahead.","og_url":"https:\/\/internationalafricanmobilization.com\/sw\/e-news\/july-2026\/","og_site_name":"International African Mobilization","article_modified_time":"2026-07-15T02:18:24+00:00","og_image":[{"width":1024,"height":680,"url":"https:\/\/internationalafricanmobilization.com\/wp-content\/uploads\/2026\/07\/iam-hero.png.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/internationalafricanmobilization.com\/ur\/e-news\/july-2026\/","url":"https:\/\/internationalafricanmobilization.com\/ur\/e-news\/july-2026\/","name":"E-News Update \u2014 July 2026 - International African Mobilization","isPartOf":{"@id":"https:\/\/internationalafricanmobilization.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/internationalafricanmobilization.com\/ur\/e-news\/july-2026\/#primaryimage"},"image":{"@id":"https:\/\/internationalafricanmobilization.com\/ur\/e-news\/july-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/internationalafricanmobilization.com\/wp-content\/uploads\/2026\/07\/iam-hero.png.jpg","datePublished":"2026-07-08T15:28:44+00:00","dateModified":"2026-07-15T02:18:24+00:00","description":"International African Mobilization's July 2026 ministry update: answered prayers, new groups, and what's ahead.","breadcrumb":{"@id":"https:\/\/internationalafricanmobilization.com\/ur\/e-news\/july-2026\/#breadcrumb"},"inLanguage":"sw","potentialAction":[{"@type":"ReadAction","target":["https:\/\/internationalafricanmobilization.com\/ur\/e-news\/july-2026\/"]}]},{"@type":"ImageObject","inLanguage":"sw","@id":"https:\/\/internationalafricanmobilization.com\/ur\/e-news\/july-2026\/#primaryimage","url":"https:\/\/internationalafricanmobilization.com\/wp-content\/uploads\/2026\/07\/iam-hero.png.jpg","contentUrl":"https:\/\/internationalafricanmobilization.com\/wp-content\/uploads\/2026\/07\/iam-hero.png.jpg","width":1024,"height":680},{"@type":"BreadcrumbList","@id":"https:\/\/internationalafricanmobilization.com\/ur\/e-news\/july-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/internationalafricanmobilization.com\/"},{"@type":"ListItem","position":2,"name":"E-News","item":"https:\/\/internationalafricanmobilization.com\/ur\/e-news\/"},{"@type":"ListItem","position":3,"name":"E-News Update \u2014 July 2026"}]},{"@type":"WebSite","@id":"https:\/\/internationalafricanmobilization.com\/#website","url":"https:\/\/internationalafricanmobilization.com\/","name":"Uhamasishaji wa Kimataifa wa Kiafrika","description":"Kumtukuza Mungu, Wanafunzi Wanaozalisha Harakati (DMM)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/internationalafricanmobilization.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sw"}]}},"_links":{"self":[{"href":"https:\/\/internationalafricanmobilization.com\/sw\/wp-json\/wp\/v2\/pages\/1606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/internationalafricanmobilization.com\/sw\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/internationalafricanmobilization.com\/sw\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/internationalafricanmobilization.com\/sw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/internationalafricanmobilization.com\/sw\/wp-json\/wp\/v2\/comments?post=1606"}],"version-history":[{"count":1,"href":"https:\/\/internationalafricanmobilization.com\/sw\/wp-json\/wp\/v2\/pages\/1606\/revisions"}],"predecessor-version":[{"id":1746,"href":"https:\/\/internationalafricanmobilization.com\/sw\/wp-json\/wp\/v2\/pages\/1606\/revisions\/1746"}],"up":[{"embeddable":true,"href":"https:\/\/internationalafricanmobilization.com\/sw\/wp-json\/wp\/v2\/pages\/15"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/internationalafricanmobilization.com\/sw\/wp-json\/wp\/v2\/media\/1266"}],"wp:attachment":[{"href":"https:\/\/internationalafricanmobilization.com\/sw\/wp-json\/wp\/v2\/media?parent=1606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}