{"id":1419,"date":"2026-07-07T12:52:24","date_gmt":"2026-07-07T12:52:24","guid":{"rendered":"https:\/\/internationalafricanmobilization.com\/training\/sail-2\/100-name-list\/"},"modified":"2026-08-13T16:48:43","modified_gmt":"2026-08-13T16:48:43","slug":"100-name-list","status":"publish","type":"page","link":"https:\/\/internationalafricanmobilization.com\/yo\/training\/sail-2\/100-name-list\/","title":{"rendered":"\u00c0k\u00f3j\u1ecd Or\u00fak\u1ecd 100"},"content":{"rendered":"<style>\n.tool-solo-video{margin-bottom:30px;box-shadow:0 4px 18px rgba(0,0,0,.15);}\n<\/style>\n\n<p><a href=\"https:\/\/internationalafricanmobilization.com\/yo\/training\/sail-2\/\">&mdash; Back to Sail 2<\/a><\/p>\n<h1>\u00c0k\u00f3j\u1ecd Or\u00fak\u1ecd 100<\/h1>\n<p>A personal list of 100 unreached or unengaged people, places, or people groups kept before you in prayer &mdash; keeping the scope of the Great Commission specific, personal, and visible every day.<\/p>\n<p>Note: clicking &ldquo;Watch this training&rdquo; above opens Z&uacute;me Session 2 at the beginning &mdash; use the right arrow (\u25b8) to advance to the 3rd video, &ldquo;Relational Stewardship &ndash; List of 100,&rdquo; for the training that matches this tool.<\/p>\n<a href=\"https:\/\/internationalafricanmobilization.com\/yo\/training\/sail-2\/\">Pada si Sail 2<\/a><a href=\"https:\/\/internationalafricanmobilization.com\/yo\/contact\/\">Beere Nipa Ik\u1eb9k\u1ecd<\/a>","protected":false},"excerpt":{"rendered":"<p>&mdash; Back to Sail 2 100 Name List A personal list of 100 unreached or unengaged people, places, or people groups kept before you in prayer &mdash; keeping the scope of the Great Commission specific, personal, and visible every day. Note: clicking &ldquo;Watch this training&rdquo; above opens Z&uacute;me Session 2 at the beginning &mdash; use&hellip;<\/p>","protected":false},"author":1,"featured_media":1266,"parent":1378,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-1419","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>100 Name List - International African Mobilization<\/title>\n<meta name=\"description\" content=\"A prayer and outreach tool: listing 100 names of people to intentionally pray for and reach.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/internationalafricanmobilization.com\/yo\/training\/sail-2\/100-name-list\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"100 Name List - International African Mobilization\" \/>\n<meta property=\"og:description\" content=\"A prayer and outreach tool: listing 100 names of people to intentionally pray for and reach.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/internationalafricanmobilization.com\/yo\/training\/sail-2\/100-name-list\/\" \/>\n<meta property=\"og:site_name\" content=\"International African Mobilization\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-13T16:48:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/internationalafricanmobilization.com\/wp-content\/uploads\/2026\/07\/iam-hero.png.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00ec\u1e63\u1eb9\u0301j\u00fa 1\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/training\\\/sail-2\\\/100-name-list\\\/\",\"url\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/training\\\/sail-2\\\/100-name-list\\\/\",\"name\":\"100 Name List - International African Mobilization\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/training\\\/sail-2\\\/100-name-list\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/training\\\/sail-2\\\/100-name-list\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/iam-hero.png.jpg\",\"datePublished\":\"2026-07-07T12:52:24+00:00\",\"dateModified\":\"2026-08-13T16:48:43+00:00\",\"description\":\"A prayer and outreach tool: listing 100 names of people to intentionally pray for and reach.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/training\\\/sail-2\\\/100-name-list\\\/#breadcrumb\"},\"inLanguage\":\"yor\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/internationalafricanmobilization.com\\\/training\\\/sail-2\\\/100-name-list\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"yor\",\"@id\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/training\\\/sail-2\\\/100-name-list\\\/#primaryimage\",\"url\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/iam-hero.png.jpg\",\"contentUrl\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/iam-hero.png.jpg\",\"width\":1024,\"height\":680},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/training\\\/sail-2\\\/100-name-list\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Training\",\"item\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/am\\\/training\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sail 2: Extraordinary Prayer\",\"item\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/training\\\/sail-2\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"100 Name List\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/#website\",\"url\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/\",\"name\":\"International African Mobilization\",\"description\":\"Glorifying God, Disciples Making Movements (DMM)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/internationalafricanmobilization.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"yor\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"100 Name List - International African Mobilization","description":"A prayer and outreach tool: listing 100 names of people to intentionally pray for and reach.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/internationalafricanmobilization.com\/yo\/training\/sail-2\/100-name-list\/","og_locale":"en_US","og_type":"article","og_title":"100 Name List - International African Mobilization","og_description":"A prayer and outreach tool: listing 100 names of people to intentionally pray for and reach.","og_url":"https:\/\/internationalafricanmobilization.com\/yo\/training\/sail-2\/100-name-list\/","og_site_name":"International African Mobilization","article_modified_time":"2026-08-13T16:48:43+00:00","og_image":[{"width":1024,"height":680,"url":"https:\/\/internationalafricanmobilization.com\/wp-content\/uploads\/2026\/07\/iam-hero.png.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"\u00ec\u1e63\u1eb9\u0301j\u00fa 1"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/internationalafricanmobilization.com\/training\/sail-2\/100-name-list\/","url":"https:\/\/internationalafricanmobilization.com\/training\/sail-2\/100-name-list\/","name":"100 Name List - International African Mobilization","isPartOf":{"@id":"https:\/\/internationalafricanmobilization.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/internationalafricanmobilization.com\/training\/sail-2\/100-name-list\/#primaryimage"},"image":{"@id":"https:\/\/internationalafricanmobilization.com\/training\/sail-2\/100-name-list\/#primaryimage"},"thumbnailUrl":"https:\/\/internationalafricanmobilization.com\/wp-content\/uploads\/2026\/07\/iam-hero.png.jpg","datePublished":"2026-07-07T12:52:24+00:00","dateModified":"2026-08-13T16:48:43+00:00","description":"A prayer and outreach tool: listing 100 names of people to intentionally pray for and reach.","breadcrumb":{"@id":"https:\/\/internationalafricanmobilization.com\/training\/sail-2\/100-name-list\/#breadcrumb"},"inLanguage":"yor","potentialAction":[{"@type":"ReadAction","target":["https:\/\/internationalafricanmobilization.com\/training\/sail-2\/100-name-list\/"]}]},{"@type":"ImageObject","inLanguage":"yor","@id":"https:\/\/internationalafricanmobilization.com\/training\/sail-2\/100-name-list\/#primaryimage","url":"https:\/\/internationalafricanmobilization.com\/wp-content\/uploads\/2026\/07\/iam-hero.png.jpg","contentUrl":"https:\/\/internationalafricanmobilization.com\/wp-content\/uploads\/2026\/07\/iam-hero.png.jpg","width":1024,"height":680},{"@type":"BreadcrumbList","@id":"https:\/\/internationalafricanmobilization.com\/training\/sail-2\/100-name-list\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/internationalafricanmobilization.com\/"},{"@type":"ListItem","position":2,"name":"Training","item":"https:\/\/internationalafricanmobilization.com\/am\/training\/"},{"@type":"ListItem","position":3,"name":"Sail 2: Extraordinary Prayer","item":"https:\/\/internationalafricanmobilization.com\/training\/sail-2\/"},{"@type":"ListItem","position":4,"name":"100 Name List"}]},{"@type":"WebSite","@id":"https:\/\/internationalafricanmobilization.com\/#website","url":"https:\/\/internationalafricanmobilization.com\/","name":"\u00ccgb\u00e9kal\u1eb9\u0300 \u00c0gb\u00e1y\u00e9 ti \u00c1f\u00edr\u00edk\u00e0","description":"F\u00edfi \u00f2go f\u00fan \u1eccl\u1ecd\u0301run, \u00c0w\u1ecdn \u1eccm\u1ecd-\u1eb9\u0300y\u00ecn \u0144 \u1e63e \u00e0w\u1ecdn \u00ec\u1e63\u00edpo (DMM)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/internationalafricanmobilization.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"yor"}]}},"_links":{"self":[{"href":"https:\/\/internationalafricanmobilization.com\/yo\/wp-json\/wp\/v2\/pages\/1419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/internationalafricanmobilization.com\/yo\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/internationalafricanmobilization.com\/yo\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/internationalafricanmobilization.com\/yo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/internationalafricanmobilization.com\/yo\/wp-json\/wp\/v2\/comments?post=1419"}],"version-history":[{"count":10,"href":"https:\/\/internationalafricanmobilization.com\/yo\/wp-json\/wp\/v2\/pages\/1419\/revisions"}],"predecessor-version":[{"id":2397,"href":"https:\/\/internationalafricanmobilization.com\/yo\/wp-json\/wp\/v2\/pages\/1419\/revisions\/2397"}],"up":[{"embeddable":true,"href":"https:\/\/internationalafricanmobilization.com\/yo\/wp-json\/wp\/v2\/pages\/1378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/internationalafricanmobilization.com\/yo\/wp-json\/wp\/v2\/media\/1266"}],"wp:attachment":[{"href":"https:\/\/internationalafricanmobilization.com\/yo\/wp-json\/wp\/v2\/media?parent=1419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}